﻿{"id":93,"date":"2023-09-13T17:24:05","date_gmt":"2023-09-13T15:24:05","guid":{"rendered":"https:\/\/iictelaviv.esteri.it\/?page_id=93"},"modified":"2026-07-13T10:42:27","modified_gmt":"2026-07-13T07:42:27","slug":"bandi-di-concorso","status":"publish","type":"page","link":"https:\/\/iictelaviv.esteri.it\/it\/amministrazione-trasparente\/bandi-di-concorso\/","title":{"rendered":"Bandi di concorso"},"content":{"rendered":"<div class=\"entry-content\">\n<p><strong>AVVISO DI ASSUNZIONE DI N.1 IMPIEGATO\/A A CONTRATTO A TEMPO INDETERMINATO DA ADIBIRE AI SERVIZI DI COLLABORATORE AMMINISTRATIVO PRESSO L\u2019ISTITUTO ITALIANO DI CULTURA DI TEL AVIV<\/strong><\/p>\n<header class=\"entry-header\">\u00c8 indetta una procedura di selezione per<strong> l\u2019assunzione di un\/a impiegato\/a a contratto a tempo indeterminato<\/strong>\u00a0da adibire ai servizi di\u00a0<strong>collaboratore amministrativo nel settore contabilit\u00e0-manifestazioni culturali-traduzione<\/strong> presso l\u2019Istituto Italiano di Cultura di Tel Aviv.<\/header>\n<header class=\"entry-header\">Per maggiori informazioni sui requisiti e sulle modalit\u00e0 di presentazione delle candidature, si prega di consultare <strong><a href=\"https:\/\/iictelaviv.esteri.it\/wp-content\/uploads\/2026\/01\/Avviso-di-assunzione-2026-1.pdf\">l\u2019avviso<\/a><\/strong>.<\/header>\n<header class=\"entry-header\">Le domande di ammissione alle prove per l\u2019assunzione, da redigersi secondo il\u00a0<strong><a href=\"https:\/\/iictelaviv.esteri.it\/wp-content\/uploads\/2026\/01\/02_Fac-simile-di-Domanda_IIC-Tel-Aviv.doc\">modulo <\/a><\/strong>disponibile al\u00a0link sotto indicato, dovranno essere presentate, con invio all\u2019indirizzo di posta elettronica <strong><a href=\"mailto:iictelaviv@esteri.it\">iictelaviv@esteri.it<\/a><\/strong>, <strong>entro e non oltre le ore 23:59 (ora di Tel Aviv)<\/strong> del giorno<strong> 9 febbraio 2026.<\/strong><\/header>\n<header>&#8211;<\/header>\n<header class=\"entry-header\"><strong>Documentazione:<\/strong><\/header>\n<ul>\n<li class=\"entry-header\"><a href=\"https:\/\/iictelaviv.esteri.it\/wp-content\/uploads\/2026\/01\/Avviso-di-assunzione-2026-1.pdf\">Avviso di assunzione 2026<\/a><\/li>\n<li class=\"entry-header\"><a href=\"https:\/\/iictelaviv.esteri.it\/wp-content\/uploads\/2026\/01\/02_Fac-simile-di-Domanda_IIC-Tel-Aviv.doc\">Modulo domanda di partecipazione<\/a><\/li>\n<li><a href=\"https:\/\/iictelaviv.esteri.it\/wp-content\/uploads\/2026\/03\/Atto-di-Delega-del-Presidente-della-Commissione_Firmato.pdf\">Atto di delega del Presidente della commissione<\/a><\/li>\n<li><a href=\"https:\/\/iictelaviv.esteri.it\/wp-content\/uploads\/2026\/03\/Atto-di-Nomina-membri-della-Commissione_firmato.pdf\">Atto di nomina della commissione<\/a><\/li>\n<li><a href=\"https:\/\/iictelaviv.esteri.it\/wp-content\/uploads\/2026\/04\/06-Dichiarazione-di-insussistenza-cause-incompatibilita-dei-membri-di-Commissione_WEBSITE.pdf\">Dichiarazione di insussistenza di cause di incompatibilit\u00e0<\/a><\/li>\n<li><a href=\"https:\/\/iictelaviv.esteri.it\/wp-content\/uploads\/2026\/03\/07-Verbale1-Chiusura-termini-domande_-PER-WEBSITE.pdf\">Verbale 1. Chiusura dei termini di presentazione delle domande<\/a><\/li>\n<li><a href=\"https:\/\/iictelaviv.esteri.it\/wp-content\/uploads\/2026\/03\/08-Verbale2-CalendarioProve_PER-WEBSITE.pdf\">Verbale 2. Calendario delle prove scritte e criteri di valutazione<\/a><\/li>\n<li><a href=\"https:\/\/iictelaviv.esteri.it\/wp-content\/uploads\/2026\/05\/Tracce_IT_HE.pdf\">Tracce delle prove scritte (tracce estratte: IT&gt;HE n. 1, HE&gt;IT n. 2)<\/a><\/li>\n<li><a href=\"https:\/\/iictelaviv.esteri.it\/wp-content\/uploads\/2026\/07\/verbale_sostituzione_membro-Commissione_dichiarazione_WEBSITE.pdf\">Sostituzione membro Commissione esaminatrice<\/a><\/li>\n<\/ul>\n<\/div>\n<p><em>Ultimo aggiornamento: 7 luglio 2026<\/em><\/p>\n<header><\/header>\n<header><\/header>\n<header><\/header>\n","protected":false},"excerpt":{"rendered":"AVVISO DI ASSUNZIONE DI N.1 IMPIEGATO\/A A CONTRATTO A TEMPO INDETERMINATO DA ADIBIRE AI SERVIZI DI COLLABORATORE AMMINISTRATIVO PRESSO L\u2019ISTITUTO ITALIANO DI CULTURA DI TEL AVIV \u00c8 indetta una procedura di selezione per l\u2019assunzione di un\/a impiegato\/a a contratto a tempo indeterminato\u00a0da adibire ai servizi di\u00a0collaboratore amministrativo nel settore contabilit\u00e0-manifestazioni culturali-traduzione presso l\u2019Istituto Italiano di [&hellip;]","protected":false},"author":1,"featured_media":0,"parent":23,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-93","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/iictelaviv.esteri.it\/it\/wp-json\/wp\/v2\/pages\/93","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iictelaviv.esteri.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iictelaviv.esteri.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iictelaviv.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iictelaviv.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=93"}],"version-history":[{"count":6,"href":"https:\/\/iictelaviv.esteri.it\/it\/wp-json\/wp\/v2\/pages\/93\/revisions"}],"predecessor-version":[{"id":21920,"href":"https:\/\/iictelaviv.esteri.it\/it\/wp-json\/wp\/v2\/pages\/93\/revisions\/21920"}],"up":[{"embeddable":true,"href":"https:\/\/iictelaviv.esteri.it\/it\/wp-json\/wp\/v2\/pages\/23"}],"wp:attachment":[{"href":"https:\/\/iictelaviv.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=93"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}